{"id":6725,"date":"2017-04-24T20:55:05","date_gmt":"2017-04-24T20:55:05","guid":{"rendered":"https:\/\/fitnfemale.de\/auf-diese-komplimente-koennen-kraftsportlerinnen-getrost-verzichten-2\/"},"modified":"2018-04-12T13:11:08","modified_gmt":"2018-04-12T12:11:08","slug":"auf-diese-komplimente-koennen-kraftsportlerinnen-getrost-verzichten-2","status":"publish","type":"post","link":"https:\/\/staging.fitnfemale.com\/deu\/auf-diese-komplimente-koennen-kraftsportlerinnen-getrost-verzichten-2\/","title":{"rendered":"Auf diese &quot;Komplimente&quot; k\u00f6nnen Kraftsportlerinnen getrost verzichten"},"content":{"rendered":"<p>Frauen, die dem Kraftsport nachgehen und dementsprechend \u00fcber eine athletische Figur und einen leistungsf\u00e4higen K\u00f6rper verf\u00fcgen, k\u00f6nnen sich in der allt\u00e4glichen Trainingspraxis vor Komplimenten in der Regel kaum retten. Das Problem an der Sache ist lediglich, dass viele dieser Komplimente bewusst zweideutig gehalten sind, was nicht minder oft zu Konflikten f\u00fchrt. Um diese Problematik ein wenig abzumildern, m\u00f6chten wir dir im Rahmen dieses Artikels sechs &#8222;Komplimente&#8220; nennen, die ihren Namen nicht wirklich verdienen.<\/p>\n<h2>1 &#8211; Mit deinen gro\u00dfen Muskeln siehst du aus wie ein ganzer Kerl<\/h2>\n<p>Viele Menschen gehen f\u00e4lschlicherweise noch immer davon aus, dass gro\u00dfe Muskeln etwas sind, \u00fcber das nur M\u00e4nner verf\u00fcgen. Die Tatsache, dass alle Menschen mehr oder minder gro\u00dfe Muskeln haben, und dass dies nichts mit dem Geschlecht zu tun hat, ist also noch immer nicht zu allen durchgedrungen. Es ist also nichts Ungew\u00f6hnliches daran, dass auch Frauen eine kr\u00e4ftige Muskulatur ausbilden k\u00f6nnen. Eine gut definierte Muskulatur ist und bleibt eine gut definierte Muskulatur und hat mit Geschlechterbindung prinzipiell ebenso wenig zu tun wie Cheeseburger mit einer gesunden Ern\u00e4hrung.<\/p>\n<h2>2 &#8211; Sch\u00f6n, dass du dein Ding durchziehst. Ich kann mich an Zeiten erinnern, da war Frauensport noch anst\u00f6\u00dfig<\/h2>\n<p>Warum werden wir eigentlich noch nach Jahrzehnten der Emanzipation auf Schritt und Tritt damit konfrontiert, was noch in der Generation unserer M\u00fctter und Gro\u00dfm\u00fctter \u00fcblich gewesen ist? Nat\u00fcrlich kann der Sport auch heute noch in vielerlei Hinsicht hart f\u00fcr Frauen sein. Das bedeutet aber noch lange nicht, dass man uns dies mit Hilfe von markigen Spr\u00fcchen st\u00e4ndig unter die Nase reiben muss.<\/p>\n<h2>3 &#8211; F\u00fcr ein M\u00e4dchen bist du ganz sch\u00f6n stark<\/h2>\n<p>Eine starke Frau ist nicht nur stark f\u00fcr ein M\u00e4dchen, sondern sie ist einfach nur stark. Was um Himmelswillen soll diese Herabw\u00fcrdigung unserer Leistungsf\u00e4higkeit? Vielleicht sollten wir auch dazu \u00fcbergehen, Komplimente nach dem Motto: \u00bbF\u00fcr einen Mann bist du ganz sch\u00f6n stark\u00ab, zu verteilen. Vielleicht w\u00fcrde dies zum gegenseitigen Verst\u00e4ndnis einen wertvollen Beitrag leisten. Da dies zugegebenerma\u00dfen nicht der Fall sein wird, w\u00e4re es auch bereits ausreichend, wenn wir uns darauf einigen k\u00f6nnten, die Leistungsf\u00e4higkeit eines Menschen von der Geschlechterrolle zu entkoppeln.<\/p>\n<h2>4 &#8211; Du siehst verdammt kr\u00e4ftig aus, schau dir nur deine Oberschenkel an<\/h2>\n<p>Ein Athlet zu sein umfasst mehr als nur einen gut austrainierten K\u00f6rper, denn die Optik ist bei weitem nicht alles. Besonders deutlich tritt dieser Fakt bei weiblichen Trainierenden hervor, die sich in erster Linie an ihrer Trainings-Performance orientieren und die optische Entwicklung diesbez\u00fcglich hintenanstellen. Jeder sollte akzeptieren, dass jeder Mensch unterschiedliche Ziele vor Augen hat, die nicht unbedingt der gedanklichen Schablone bestimmter Personengruppen entspricht.<\/p>\n<h2>5 &#8211; Du musst bestimmt ganz sch\u00f6n hart arbeiten, um deinen unglaublichen K\u00f6rper in Form zu halten<\/h2>\n<p>Es gibt keinen K\u00f6rper, der die perfekte Form hat, was schlicht und ergreifend daran liegt, dass sich die subjektive Perfektion aus zahlreichen unterschiedlichen Merkmalen zusammensetzen kann. Nur weil ein K\u00f6rper in den Augen eines bestimmten Mannes perfekt erscheint, muss sich die Leistungsf\u00e4higkeit noch lange nicht mit der Optik decken.<\/p>\n<h2>6 &#8211; Dein Bizeps w\u00e4chst mit jeder Trainingseinheit<\/h2>\n<p>Wir verf\u00fcgen alle genetisch bedingt \u00fcber eine leicht voneinander abweichend K\u00f6rperkomposition, was dazu f\u00fchrt, dass manche Menschen trotz harter Arbeit niemals massive Muskeln ihr Eigen nennen d\u00fcrfen. Folglich sollte sich niemand dazu verleiten lassen, die optischen Erfolge anderer Athletinnen und Athleten an eigenen subjektiven aber unpassenden Ma\u00dfst\u00e4ben zu messen. Merkt es euch, jeder Mensch sieht aus, wie er aussehen soll, alles andere ist Detailarbeit.<\/p>\n<div class=\"woocommerce columns-4\"><div class=\"products row row-small large-columns-4 medium-columns-3 small-columns-2 has-equal-box-heights equalize-box\">\n<div class=\"product-small col has-hover product type-product post-8097 status-publish first instock product_cat-promo-40 product_cat-basic product_cat-food product_cat-snack has-post-thumbnail taxable shipping-taxable purchasable product-type-variable has-default-attributes\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/staging.fitnfemale.com\/deu\/produkt\/flavourit\/\">\n\t\t\t\t\t<img decoding=\"async\" width=\"247\" height=\"296\" src=\"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/flavourite25-247x296.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Flavourite25\" \/><img decoding=\"async\" width=\"247\" height=\"296\" src=\"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/flavourite-closeup-10-247x296.webp\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Flavourite closeup\" aria-hidden=\"true\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\"><p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/staging.fitnfemale.com\/deu\/produkt\/flavourit\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Flavourit<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"wcpbc-price wcpbc-price-8097\" data-product-id=\"8097\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>\u00a015.90<\/bdi><\/span> <small class=\"woocommerce-price-suffix\">inkl. MWST<\/small><\/span><\/span>\n<\/div>\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/staging.fitnfemale.com\/deu\/produkt\/flavourit\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_8097\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"8097\" data-product_sku=\"\" aria-label=\"Optionen f\u00fcr \u201cFlavourit\u201d ausw\u00e4hlen\u201d\" rel=\"nofollow\" data-product_image_src=\"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/flavourite25-247x296.jpg\" data-product_image_width=\"247\" data-product_image_height=\"296\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Optionen ausw\u00e4hlen<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_8097\" class=\"screen-reader-text\">\n\t\tDieses Produkt ist in mehreren Varianten erh\u00e4ltlich. Die Optionen k\u00f6nnen auf der Produktseite ausgew\u00e4hlt werden.\t<\/span>\n\t<\/div>\n<\/div><\/div><!-- row -->\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Frauen, die dem Kraftsport nachgehen und dementsprechend \u00fcber eine athletische Figur und einen leistungsf\u00e4higen K\u00f6rper verf\u00fcgen, k\u00f6nnen sich in der allt\u00e4glichen Trainingspraxis vor Komplimenten in der Regel kaum retten. Das Problem an der Sache ist lediglich, dass viele dieser Komplimente bewusst zweideutig gehalten sind, was nicht minder oft zu Konflikten f\u00fchrt.<\/p>","protected":false},"author":1,"featured_media":10483,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"slim_seo":{"title":"Auf diese &quot;Komplimente&quot; k\u00f6nnen Kraftsportlerinnen getrost verzichten - FitNFemale\u00ae","description":"Frauen, die dem Kraftsport nachgehen und dementsprechend \u00fcber eine athletische Figur und einen leistungsf\u00e4higen K\u00f6rper verf\u00fcgen, k\u00f6nnen sich in der allt\u00e4glichen"},"footnotes":""},"categories":[2],"tags":[688,11,35],"class_list":["post-6725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-training","tag-krafttraining","tag-muskelaufbau","tag-workout"],"_links":{"self":[{"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/posts\/6725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/comments?post=6725"}],"version-history":[{"count":0,"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/posts\/6725\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/media\/10483"}],"wp:attachment":[{"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/media?parent=6725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/categories?post=6725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/tags?post=6725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}