{"id":91708,"date":"2018-11-15T22:00:15","date_gmt":"2018-11-15T21:00:15","guid":{"rendered":"https:\/\/fitnfemale.com\/wp-content\/uploads\/green-fiber-side2.png"},"modified":"2018-11-15T22:00:15","modified_gmt":"2018-11-15T21:00:15","slug":"green-fiber-side2","status":"inherit","type":"attachment","link":"https:\/\/staging.fitnfemale.com\/deu\/green-fiber-side2\/","title":{"rendered":"green fiber side2"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"slim_seo":{"title":"green fiber side2 - FitNFemale\u00ae","description":""}},"class_list":["post-91708","attachment","type-attachment","status-inherit","hentry"],"_iconic_woothumbs_media":"","_iconic_woothumbs_media_aspect_ratio":"","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2.png'><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-400x400.png\" class=\"attachment-medium size-medium\" alt=\"Green fiber side2\" srcset=\"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-400x400.png 400w, https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-200x200.png 200w, https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-510x510.png 510w, https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-800x800.png 800w, https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-280x280.png 280w, https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-768x768.png 768w, https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-12x12.png 12w, https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2.png 1000w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1000,"height":1000,"file":"green-fiber-side2.png","filesize":261725,"sizes":{"woocommerce_thumbnail":{"file":"green-fiber-side2-247x296.png","width":247,"height":296,"filesize":30513,"uncropped":false,"mime_type":"image\/png","source_url":"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-247x296.png"},"woocommerce_gallery_thumbnail":{"file":"green-fiber-side2-200x200.png","width":200,"height":200,"filesize":40878,"mime_type":"image\/png","source_url":"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-200x200.png"},"woocommerce_single":{"file":"green-fiber-side2-510x510.png","width":510,"height":510,"filesize":275121,"mime_type":"image\/png","source_url":"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-510x510.png"},"medium":{"file":"green-fiber-side2-400x400.png","width":400,"height":400,"filesize":134279,"mime_type":"image\/png","source_url":"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-400x400.png"},"large":{"file":"green-fiber-side2-800x800.png","width":800,"height":800,"filesize":502943,"mime_type":"image\/png","source_url":"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-800x800.png"},"thumbnail":{"file":"green-fiber-side2-280x280.png","width":280,"height":280,"filesize":68761,"mime_type":"image\/png","source_url":"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-280x280.png"},"medium_large":{"file":"green-fiber-side2-768x768.png","width":768,"height":768,"filesize":466053,"mime_type":"image\/png","source_url":"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-768x768.png"},"trp-custom-language-flag":{"file":"green-fiber-side2-12x12.png","width":12,"height":12,"filesize":457,"mime_type":"image\/png","source_url":"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2-12x12.png"},"full":{"file":"green-fiber-side2.png","width":1000,"height":1000,"mime_type":"image\/png","source_url":"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/staging.fitnfemale.com\/wp-content\/uploads\/green-fiber-side2.png","_links":{"self":[{"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/media\/91708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.fitnfemale.com\/deu\/wp-json\/wp\/v2\/comments?post=91708"}]}}